{"id":135246,"date":"2026-07-15T01:08:01","date_gmt":"2026-07-14T23:08:01","guid":{"rendered":"https:\/\/www.eosart.ch\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/"},"modified":"2026-07-15T01:08:12","modified_gmt":"2026-07-14T23:08:12","slug":"illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2","status":"publish","type":"product","link":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/","title":{"rendered":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870."},"content":{"rendered":"<p>\u00a0\u00a0 Sechsel\u00e4uten. \u2013  Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.\u00a0 Z\u00fcrich, 1870. Lithographie. Blattgr\u00f6sse: 65 x 51 cm.<br \/>\nHonegger 34. &#8211; Nr. II (von 5). \u2013 Darstellungen aus H\u00f6hepunkten fr\u00fcherer Umz\u00fcge mit 4 Streifen. \u2013 Knitterfaltig, mit kleineren Einrissen und stockfleckig.<\/p>\n<p>+ Wichtig: F\u00fcr unsere Kunden in der EU erfolgt der Versand alle 14 Tage verzollt ab Deutschland \/ Postbank-Konto in Deutschland vorhanden +<\/p>\n<p><strong>Bestellnummer<\/strong>: 904CG<\/p>\n<p><span class=\"schlagwort\">Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland, Sechsel\u00e4uten, Turicensia &#8211; Stadt Z\u00fcrich \/ Zurich City, Zunftwesen \u2013 Z\u00fcnfte, Z\u00fcrich Kanton<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>    Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.<\/p>\n","protected":false},"featured_media":3140270,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[176],"product_tag":[],"class_list":["post-135246","product","type-product","status-publish","has-post-thumbnail","product_cat-helvetica-schweiz-books-and-prints-pertaining-switzerland","first","instock","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EOS ART Benz -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz\" \/>\n\t\t<meta property=\"og:description\" content=\"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T23:08:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T23:08:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"name\":\"Store\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/helvetica-schweiz-books-and-prints-pertaining-switzerland\\\/#listItem\",\"name\":\"Helvetica \\u2013 Schweiz \\\/ Books and prints pertaining Switzerland\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/helvetica-schweiz-books-and-prints-pertaining-switzerland\\\/#listItem\",\"position\":3,\"name\":\"Helvetica \\u2013 Schweiz \\\/ Books and prints pertaining Switzerland\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/helvetica-schweiz-books-and-prints-pertaining-switzerland\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#listItem\",\"name\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"name\":\"Store\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#listItem\",\"position\":4,\"name\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/helvetica-schweiz-books-and-prints-pertaining-switzerland\\\/#listItem\",\"name\":\"Helvetica \\u2013 Schweiz \\\/ Books and prints pertaining Switzerland\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#itempage\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/\",\"name\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870. - EOS ART Benz\",\"description\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/904CG.jpg\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#mainImage\",\"width\":1200,\"height\":936,\"caption\":\"- Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#mainImage\"},\"datePublished\":\"2026-07-15T01:08:01+02:00\",\"dateModified\":\"2026-07-15T01:08:12+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#organization\",\"name\":\"EOS ART Benz\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/\",\"name\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870. - EOS ART Benz\",\"description\":\"Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/904CG.jpg\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#mainImage\",\"width\":1200,\"height\":936,\"caption\":\"- Illustration zur Geschichte des Sechsel\\u00e4utens. Festzug der Vereinigten Z\\u00fcnfte Z\\u00fcrichs am 4. April 1870.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\\\/#mainImage\"},\"datePublished\":\"2026-07-15T01:08:01+02:00\",\"dateModified\":\"2026-07-15T01:08:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\",\"name\":\"EOS ART Benz\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz<\/title>\n\n","aioseo_head_json":{"title":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz","description":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","canonical_url":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.eosart.ch\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","name":"Store"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","position":2,"name":"Store","item":"https:\/\/www.eosart.ch\/en\/store\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/#listItem","name":"Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/#listItem","position":3,"name":"Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland","item":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#listItem","name":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","name":"Store"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#listItem","position":4,"name":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/#listItem","name":"Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland"}}]},{"@type":"ItemPage","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#itempage","url":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/","name":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz","description":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.eosart.ch\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.eosart.ch\/wp-content\/uploads\/2026\/07\/904CG.jpg","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#mainImage","width":1200,"height":936,"caption":"- Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870."},"primaryImageOfPage":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#mainImage"},"datePublished":"2026-07-15T01:08:01+02:00","dateModified":"2026-07-15T01:08:12+02:00"},{"@type":"Organization","@id":"https:\/\/www.eosart.ch\/en\/#organization","name":"EOS ART Benz","url":"https:\/\/www.eosart.ch\/en\/"},{"@type":"WebPage","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#webpage","url":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/","name":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz","description":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.eosart.ch\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.eosart.ch\/wp-content\/uploads\/2026\/07\/904CG.jpg","@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#mainImage","width":1200,"height":936,"caption":"- Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870."},"primaryImageOfPage":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/#mainImage"},"datePublished":"2026-07-15T01:08:01+02:00","dateModified":"2026-07-15T01:08:12+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eosart.ch\/en\/#website","url":"https:\/\/www.eosart.ch\/en\/","name":"EOS ART Benz","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.eosart.ch\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"EOS ART Benz -","og:type":"article","og:title":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz","og:description":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","og:url":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/","article:published_time":"2026-07-14T23:08:01+00:00","article:modified_time":"2026-07-14T23:08:12+00:00","twitter:card":"summary_large_image","twitter:title":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870. - EOS ART Benz","twitter:description":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870."},"aioseo_meta_data":{"post_id":"135246","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-11-15 13:04:25","updated":"2026-07-14 23:08:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/store\/\" title=\"Store\">Store<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/\" title=\"Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland\">Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tIllustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eosart.ch\/en\/"},{"label":"Store","link":"https:\/\/www.eosart.ch\/en\/store\/"},{"label":"Helvetica \u2013 Schweiz \/ Books and prints pertaining Switzerland","link":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/helvetica-schweiz-books-and-prints-pertaining-switzerland\/"},{"label":"Illustration zur Geschichte des Sechsel\u00e4utens. Festzug der Vereinigten Z\u00fcnfte Z\u00fcrichs am 4. April 1870.","link":"https:\/\/www.eosart.ch\/en\/produkt\/illustration-zur-geschichte-des-sechselaeutens-festzug-der-vereinigten-zuenfte-zuerichs-am-4-april-1870-2\/"}],"_links":{"self":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product\/135246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/comments?post=135246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/media\/3140270"}],"wp:attachment":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/media?parent=135246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_brand?post=135246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_cat?post=135246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_tag?post=135246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}