{"id":1002,"date":"2026-07-15T00:03:32","date_gmt":"2026-07-14T22:03:32","guid":{"rendered":"http:\/\/eosart.ch.w0153304.kasserver.com\/produkt\/fischerszene-am-meer\/"},"modified":"2026-07-15T00:03:46","modified_gmt":"2026-07-14T22:03:46","slug":"fischerszene-am-meer","status":"publish","type":"product","link":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/","title":{"rendered":"Fischerszene am Meer."},"content":{"rendered":"<p>  Fischerszene am Meer.\u00a0  Farbige Lithographie. Bildformat: 63 x 88 cm.<br \/>\nSchulwandbild.- Stockfleckig, leicht knitterfaltig.- Monogamiert: A. Fr.<\/p>\n<p>+ Wichtig: F\u00fcr unsere Kunden in der EU erfolgt der Versand alle 14 Tage verzollt ab Deutschland \/ Postbank-Konto in Deutschland vorhanden +<\/p>\n<p><strong>Bestellnummer<\/strong>: 62DG<\/p>\n<p><span class=\"schlagwort\">Schulwandbilder \/ Wall charts, Fischen &#8211; Angeln &#8211; Fischerei \/ Fishing &#8211; Fishery, K\u00fcste \/ Coast, Schulwandbild \/ Wall chart<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>    Fischerszene am Meer.<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[146],"product_tag":[],"class_list":["post-1002","product","type-product","status-publish","product_cat-schulwandbilder-wall-charts","first","instock","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fischerszene am Meer.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EOS ART Benz -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fischerszene am Meer. - EOS ART Benz\" \/>\n\t\t<meta property=\"og:description\" content=\"Fischerszene am Meer.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T22:03:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T22:03:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fischerszene am Meer. - EOS ART Benz\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fischerszene am Meer.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"name\":\"Store\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/schulwandbilder-wall-charts\\\/#listItem\",\"name\":\"\\ufeffSchulwandbilder \\\/ Wall charts\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/schulwandbilder-wall-charts\\\/#listItem\",\"position\":3,\"name\":\"\\ufeffSchulwandbilder \\\/ Wall charts\",\"item\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/schulwandbilder-wall-charts\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#listItem\",\"name\":\"Fischerszene am Meer.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/store\\\/#listItem\",\"name\":\"Store\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#listItem\",\"position\":4,\"name\":\"Fischerszene am Meer.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt-kategorie\\\/schulwandbilder-wall-charts\\\/#listItem\",\"name\":\"\\ufeffSchulwandbilder \\\/ Wall charts\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#itempage\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/\",\"name\":\"Fischerszene am Meer. - EOS ART Benz\",\"description\":\"Fischerszene am Meer.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#breadcrumblist\"},\"datePublished\":\"2026-07-15T00:03:32+02:00\",\"dateModified\":\"2026-07-15T00:03:46+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#organization\",\"name\":\"EOS ART Benz\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/\",\"name\":\"Fischerszene am Meer. - EOS ART Benz\",\"description\":\"Fischerszene am Meer.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/produkt\\\/fischerszene-am-meer\\\/#breadcrumblist\"},\"datePublished\":\"2026-07-15T00:03:32+02:00\",\"dateModified\":\"2026-07-15T00:03:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/\",\"name\":\"EOS ART Benz\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eosart.ch\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Fischerszene am Meer. - EOS ART Benz<\/title>\n\n","aioseo_head_json":{"title":"Fischerszene am Meer. - EOS ART Benz","description":"Fischerszene am Meer.","canonical_url":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.eosart.ch\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","name":"Store"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","position":2,"name":"Store","item":"https:\/\/www.eosart.ch\/en\/store\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/#listItem","name":"\ufeffSchulwandbilder \/ Wall charts"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/#listItem","position":3,"name":"\ufeffSchulwandbilder \/ Wall charts","item":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#listItem","name":"Fischerszene am Meer."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/store\/#listItem","name":"Store"}},{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#listItem","position":4,"name":"Fischerszene am Meer.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/#listItem","name":"\ufeffSchulwandbilder \/ Wall charts"}}]},{"@type":"ItemPage","@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#itempage","url":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/","name":"Fischerszene am Meer. - EOS ART Benz","description":"Fischerszene am Meer.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.eosart.ch\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#breadcrumblist"},"datePublished":"2026-07-15T00:03:32+02:00","dateModified":"2026-07-15T00:03:46+02:00"},{"@type":"Organization","@id":"https:\/\/www.eosart.ch\/en\/#organization","name":"EOS ART Benz","url":"https:\/\/www.eosart.ch\/en\/"},{"@type":"WebPage","@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#webpage","url":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/","name":"Fischerszene am Meer. - EOS ART Benz","description":"Fischerszene am Meer.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.eosart.ch\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/#breadcrumblist"},"datePublished":"2026-07-15T00:03:32+02:00","dateModified":"2026-07-15T00:03:46+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eosart.ch\/en\/#website","url":"https:\/\/www.eosart.ch\/en\/","name":"EOS ART Benz","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.eosart.ch\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"EOS ART Benz -","og:type":"article","og:title":"Fischerszene am Meer. - EOS ART Benz","og:description":"Fischerszene am Meer.","og:url":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/","article:published_time":"2026-07-14T22:03:32+00:00","article:modified_time":"2026-07-14T22:03:46+00:00","twitter:card":"summary_large_image","twitter:title":"Fischerszene am Meer. - EOS ART Benz","twitter:description":"Fischerszene am Meer."},"aioseo_meta_data":{"post_id":"1002","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-11-15 10:39:13","updated":"2026-07-14 22:03:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/store\/\" title=\"Store\">Store<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/\" title=\"\ufeffSchulwandbilder \/ Wall charts\">\ufeffSchulwandbilder \/ Wall charts<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tFischerszene am Meer.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eosart.ch\/en\/"},{"label":"Store","link":"https:\/\/www.eosart.ch\/en\/store\/"},{"label":"\ufeffSchulwandbilder \/ Wall charts","link":"https:\/\/www.eosart.ch\/en\/produkt-kategorie\/schulwandbilder-wall-charts\/"},{"label":"Fischerszene am Meer.","link":"https:\/\/www.eosart.ch\/en\/produkt\/fischerszene-am-meer\/"}],"_links":{"self":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product\/1002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/comments?post=1002"}],"wp:attachment":[{"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/media?parent=1002"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_brand?post=1002"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_cat?post=1002"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eosart.ch\/en\/wp-json\/wp\/v2\/product_tag?post=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}